{"id":3640,"date":"2025-11-13T21:04:19","date_gmt":"2025-11-13T20:04:19","guid":{"rendered":"https:\/\/empresasyeventos.com.uy\/?p=3640"},"modified":"2025-11-13T21:04:21","modified_gmt":"2025-11-13T20:04:21","slug":"daniel-habif-llega-por-primera-vez-a-uruguay-con-su-ascender-world-tour-2025","status":"publish","type":"post","link":"https:\/\/empresasyeventos.com.uy\/index.php\/2025\/11\/13\/daniel-habif-llega-por-primera-vez-a-uruguay-con-su-ascender-world-tour-2025\/","title":{"rendered":"Daniel Habif llega por primera vez a Uruguay con su \u00abAscender World Tour 2025\u00bb"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El reconocido conferencista, escritor y creador de contenidos Daniel Habif, considerado uno de los oradores m\u00e1s influyentes de habla hispana, llegar\u00e1 por primera vez a Uruguay con su impactante gira internacional \u00abAscender World Tour 2025\u00bb,<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">una experiencia transformadora que invita a reconectar con la fuerza interior y el prop\u00f3sito de vida.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El encuentro ser\u00e1 el s\u00e1bado 15 de noviembre en el Teatro Metro de Montevideo, donde Habif presentar\u00e1 una conferencia cargada de inspiraci\u00f3n, energ\u00eda y reflexi\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las entradas ya est\u00e1n a la venta a trav\u00e9s de Red Tickets, con valores que van desde $2.900 a $4.500, y con sectores VIP exclusivos con cupos limitados que incluyen la oportunidad de participar en un Meet &amp; Greet con el autor.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Autor de los bestsellers Inquebrantables, Las trampas del miedo y Ruge \u2014con m\u00e1s de un mill\u00f3n de copias vendidas\u2014, Habif combina la oratoria, el arte esc\u00e9nico y la psicolog\u00eda para ofrecer un mensaje profundo, emotivo y esperanzador.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abAscender es un llamado a levantarse, a reinventarse y a volver a creer en uno mismo. No importa cu\u00e1n duro haya sido el camino, siempre se puede subir un pelda\u00f1o m\u00e1s\u00bb, expresa Habif sobre su nueva gira.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"696\" height=\"393\" data-attachment-id=\"3641\" data-permalink=\"https:\/\/empresasyeventos.com.uy\/index.php\/2025\/11\/13\/daniel-habif-llega-por-primera-vez-a-uruguay-con-su-ascender-world-tour-2025\/daniel-habif-2\/\" data-orig-file=\"https:\/\/i0.wp.com\/empresasyeventos.com.uy\/wp-content\/uploads\/2025\/11\/Daniel-Habif-2.jpg?fit=800%2C452&amp;ssl=1\" data-orig-size=\"800,452\" data-comments-opened=\"0\" data-image-title=\"Daniel Habif\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/empresasyeventos.com.uy\/wp-content\/uploads\/2025\/11\/Daniel-Habif-2.jpg?fit=800%2C452&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/empresasyeventos.com.uy\/wp-content\/uploads\/2025\/11\/Daniel-Habif-2.jpg?resize=696%2C393&#038;ssl=1\" alt=\"\" class=\"wp-image-3641\" srcset=\"https:\/\/i0.wp.com\/empresasyeventos.com.uy\/wp-content\/uploads\/2025\/11\/Daniel-Habif-2.jpg?w=800&amp;ssl=1 800w, https:\/\/i0.wp.com\/empresasyeventos.com.uy\/wp-content\/uploads\/2025\/11\/Daniel-Habif-2.jpg?resize=768%2C434&amp;ssl=1 768w, https:\/\/i0.wp.com\/empresasyeventos.com.uy\/wp-content\/uploads\/2025\/11\/Daniel-Habif-2.jpg?resize=150%2C85&amp;ssl=1 150w, https:\/\/i0.wp.com\/empresasyeventos.com.uy\/wp-content\/uploads\/2025\/11\/Daniel-Habif-2.jpg?resize=300%2C170&amp;ssl=1 300w, https:\/\/i0.wp.com\/empresasyeventos.com.uy\/wp-content\/uploads\/2025\/11\/Daniel-Habif-2.jpg?resize=696%2C393&amp;ssl=1 696w\" sizes=\"auto, (max-width: 696px) 100vw, 696px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>El reconocido conferencista, escritor y creador de contenidos Daniel Habif, considerado uno de los oradores m\u00e1s influyentes de habla hispana, llegar\u00e1 por primera vez a Uruguay con su impactante gira [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3642,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[57],"tags":[],"class_list":["post-3640","post","type-post","status-publish","format-standard","has-post-thumbnail","category-eventos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Daniel Habif llega por primera vez a Uruguay con su &quot;Ascender World Tour 2025&quot; - Empresas &amp; Eventos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/empresasyeventos.com.uy\/index.php\/2025\/11\/13\/daniel-habif-llega-por-primera-vez-a-uruguay-con-su-ascender-world-tour-2025\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Daniel Habif llega por primera vez a Uruguay con su &quot;Ascender World Tour 2025&quot; - Empresas &amp; Eventos\" \/>\n<meta property=\"og:description\" content=\"El reconocido conferencista, escritor y creador de contenidos Daniel Habif, considerado uno de los oradores m\u00e1s influyentes de habla hispana, llegar\u00e1 por primera vez a Uruguay con su impactante gira [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/empresasyeventos.com.uy\/index.php\/2025\/11\/13\/daniel-habif-llega-por-primera-vez-a-uruguay-con-su-ascender-world-tour-2025\/\" \/>\n<meta property=\"og:site_name\" content=\"Empresas &amp; Eventos\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-13T20:04:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-13T20:04:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/empresasyeventos.com.uy\/wp-content\/uploads\/2025\/11\/Daniel-Habif-e1763064209974.jpg?fit=800%2C578&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"578\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Alvaro\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alvaro\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/empresasyeventos.com.uy\\\/index.php\\\/2025\\\/11\\\/13\\\/daniel-habif-llega-por-primera-vez-a-uruguay-con-su-ascender-world-tour-2025\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/empresasyeventos.com.uy\\\/index.php\\\/2025\\\/11\\\/13\\\/daniel-habif-llega-por-primera-vez-a-uruguay-con-su-ascender-world-tour-2025\\\/\"},\"author\":{\"name\":\"Alvaro\",\"@id\":\"https:\\\/\\\/empresasyeventos.com.uy\\\/#\\\/schema\\\/person\\\/bad32f4c82dc0dcc552d9c237c4eabe2\"},\"headline\":\"Daniel Habif llega por primera vez a Uruguay con su \u00abAscender World Tour 2025\u00bb\",\"datePublished\":\"2025-11-13T20:04:19+00:00\",\"dateModified\":\"2025-11-13T20:04:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/empresasyeventos.com.uy\\\/index.php\\\/2025\\\/11\\\/13\\\/daniel-habif-llega-por-primera-vez-a-uruguay-con-su-ascender-world-tour-2025\\\/\"},\"wordCount\":216,\"image\":{\"@id\":\"https:\\\/\\\/empresasyeventos.com.uy\\\/index.php\\\/2025\\\/11\\\/13\\\/daniel-habif-llega-por-primera-vez-a-uruguay-con-su-ascender-world-tour-2025\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/empresasyeventos.com.uy\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Daniel-Habif-e1763064209974.jpg?fit=800%2C578&ssl=1\",\"articleSection\":[\"Eventos\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/empresasyeventos.com.uy\\\/index.php\\\/2025\\\/11\\\/13\\\/daniel-habif-llega-por-primera-vez-a-uruguay-con-su-ascender-world-tour-2025\\\/\",\"url\":\"https:\\\/\\\/empresasyeventos.com.uy\\\/index.php\\\/2025\\\/11\\\/13\\\/daniel-habif-llega-por-primera-vez-a-uruguay-con-su-ascender-world-tour-2025\\\/\",\"name\":\"Daniel Habif llega por primera vez a Uruguay con su \\\"Ascender World Tour 2025\\\" - Empresas &amp; Eventos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/empresasyeventos.com.uy\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/empresasyeventos.com.uy\\\/index.php\\\/2025\\\/11\\\/13\\\/daniel-habif-llega-por-primera-vez-a-uruguay-con-su-ascender-world-tour-2025\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/empresasyeventos.com.uy\\\/index.php\\\/2025\\\/11\\\/13\\\/daniel-habif-llega-por-primera-vez-a-uruguay-con-su-ascender-world-tour-2025\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/empresasyeventos.com.uy\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Daniel-Habif-e1763064209974.jpg?fit=800%2C578&ssl=1\",\"datePublished\":\"2025-11-13T20:04:19+00:00\",\"dateModified\":\"2025-11-13T20:04:21+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/empresasyeventos.com.uy\\\/#\\\/schema\\\/person\\\/bad32f4c82dc0dcc552d9c237c4eabe2\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/empresasyeventos.com.uy\\\/index.php\\\/2025\\\/11\\\/13\\\/daniel-habif-llega-por-primera-vez-a-uruguay-con-su-ascender-world-tour-2025\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/empresasyeventos.com.uy\\\/index.php\\\/2025\\\/11\\\/13\\\/daniel-habif-llega-por-primera-vez-a-uruguay-con-su-ascender-world-tour-2025\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/empresasyeventos.com.uy\\\/index.php\\\/2025\\\/11\\\/13\\\/daniel-habif-llega-por-primera-vez-a-uruguay-con-su-ascender-world-tour-2025\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/empresasyeventos.com.uy\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Daniel-Habif-e1763064209974.jpg?fit=800%2C578&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/empresasyeventos.com.uy\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Daniel-Habif-e1763064209974.jpg?fit=800%2C578&ssl=1\",\"width\":800,\"height\":578},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/empresasyeventos.com.uy\\\/index.php\\\/2025\\\/11\\\/13\\\/daniel-habif-llega-por-primera-vez-a-uruguay-con-su-ascender-world-tour-2025\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/empresasyeventos.com.uy\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Daniel Habif llega por primera vez a Uruguay con su \u00abAscender World Tour 2025\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/empresasyeventos.com.uy\\\/#website\",\"url\":\"https:\\\/\\\/empresasyeventos.com.uy\\\/\",\"name\":\"Empresas &amp; Eventos\",\"description\":\"Portal de noticias de Empresas y Eventos\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/empresasyeventos.com.uy\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/empresasyeventos.com.uy\\\/#\\\/schema\\\/person\\\/bad32f4c82dc0dcc552d9c237c4eabe2\",\"name\":\"Alvaro\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/37aed957d094e6ff419d8d77fbf4778c8ca0066d25878f7d9ad4d0a724703223?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/37aed957d094e6ff419d8d77fbf4778c8ca0066d25878f7d9ad4d0a724703223?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/37aed957d094e6ff419d8d77fbf4778c8ca0066d25878f7d9ad4d0a724703223?s=96&d=mm&r=g\",\"caption\":\"Alvaro\"},\"url\":\"https:\\\/\\\/empresasyeventos.com.uy\\\/index.php\\\/author\\\/alvaro\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Daniel Habif llega por primera vez a Uruguay con su \"Ascender World Tour 2025\" - Empresas &amp; Eventos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/empresasyeventos.com.uy\/index.php\/2025\/11\/13\/daniel-habif-llega-por-primera-vez-a-uruguay-con-su-ascender-world-tour-2025\/","og_locale":"es_ES","og_type":"article","og_title":"Daniel Habif llega por primera vez a Uruguay con su \"Ascender World Tour 2025\" - Empresas &amp; Eventos","og_description":"El reconocido conferencista, escritor y creador de contenidos Daniel Habif, considerado uno de los oradores m\u00e1s influyentes de habla hispana, llegar\u00e1 por primera vez a Uruguay con su impactante gira [&hellip;]","og_url":"https:\/\/empresasyeventos.com.uy\/index.php\/2025\/11\/13\/daniel-habif-llega-por-primera-vez-a-uruguay-con-su-ascender-world-tour-2025\/","og_site_name":"Empresas &amp; Eventos","article_published_time":"2025-11-13T20:04:19+00:00","article_modified_time":"2025-11-13T20:04:21+00:00","og_image":[{"width":800,"height":578,"url":"https:\/\/i0.wp.com\/empresasyeventos.com.uy\/wp-content\/uploads\/2025\/11\/Daniel-Habif-e1763064209974.jpg?fit=800%2C578&ssl=1","type":"image\/jpeg"}],"author":"Alvaro","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Alvaro","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/empresasyeventos.com.uy\/index.php\/2025\/11\/13\/daniel-habif-llega-por-primera-vez-a-uruguay-con-su-ascender-world-tour-2025\/#article","isPartOf":{"@id":"https:\/\/empresasyeventos.com.uy\/index.php\/2025\/11\/13\/daniel-habif-llega-por-primera-vez-a-uruguay-con-su-ascender-world-tour-2025\/"},"author":{"name":"Alvaro","@id":"https:\/\/empresasyeventos.com.uy\/#\/schema\/person\/bad32f4c82dc0dcc552d9c237c4eabe2"},"headline":"Daniel Habif llega por primera vez a Uruguay con su \u00abAscender World Tour 2025\u00bb","datePublished":"2025-11-13T20:04:19+00:00","dateModified":"2025-11-13T20:04:21+00:00","mainEntityOfPage":{"@id":"https:\/\/empresasyeventos.com.uy\/index.php\/2025\/11\/13\/daniel-habif-llega-por-primera-vez-a-uruguay-con-su-ascender-world-tour-2025\/"},"wordCount":216,"image":{"@id":"https:\/\/empresasyeventos.com.uy\/index.php\/2025\/11\/13\/daniel-habif-llega-por-primera-vez-a-uruguay-con-su-ascender-world-tour-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/empresasyeventos.com.uy\/wp-content\/uploads\/2025\/11\/Daniel-Habif-e1763064209974.jpg?fit=800%2C578&ssl=1","articleSection":["Eventos"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/empresasyeventos.com.uy\/index.php\/2025\/11\/13\/daniel-habif-llega-por-primera-vez-a-uruguay-con-su-ascender-world-tour-2025\/","url":"https:\/\/empresasyeventos.com.uy\/index.php\/2025\/11\/13\/daniel-habif-llega-por-primera-vez-a-uruguay-con-su-ascender-world-tour-2025\/","name":"Daniel Habif llega por primera vez a Uruguay con su \"Ascender World Tour 2025\" - Empresas &amp; Eventos","isPartOf":{"@id":"https:\/\/empresasyeventos.com.uy\/#website"},"primaryImageOfPage":{"@id":"https:\/\/empresasyeventos.com.uy\/index.php\/2025\/11\/13\/daniel-habif-llega-por-primera-vez-a-uruguay-con-su-ascender-world-tour-2025\/#primaryimage"},"image":{"@id":"https:\/\/empresasyeventos.com.uy\/index.php\/2025\/11\/13\/daniel-habif-llega-por-primera-vez-a-uruguay-con-su-ascender-world-tour-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/empresasyeventos.com.uy\/wp-content\/uploads\/2025\/11\/Daniel-Habif-e1763064209974.jpg?fit=800%2C578&ssl=1","datePublished":"2025-11-13T20:04:19+00:00","dateModified":"2025-11-13T20:04:21+00:00","author":{"@id":"https:\/\/empresasyeventos.com.uy\/#\/schema\/person\/bad32f4c82dc0dcc552d9c237c4eabe2"},"breadcrumb":{"@id":"https:\/\/empresasyeventos.com.uy\/index.php\/2025\/11\/13\/daniel-habif-llega-por-primera-vez-a-uruguay-con-su-ascender-world-tour-2025\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/empresasyeventos.com.uy\/index.php\/2025\/11\/13\/daniel-habif-llega-por-primera-vez-a-uruguay-con-su-ascender-world-tour-2025\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/empresasyeventos.com.uy\/index.php\/2025\/11\/13\/daniel-habif-llega-por-primera-vez-a-uruguay-con-su-ascender-world-tour-2025\/#primaryimage","url":"https:\/\/i0.wp.com\/empresasyeventos.com.uy\/wp-content\/uploads\/2025\/11\/Daniel-Habif-e1763064209974.jpg?fit=800%2C578&ssl=1","contentUrl":"https:\/\/i0.wp.com\/empresasyeventos.com.uy\/wp-content\/uploads\/2025\/11\/Daniel-Habif-e1763064209974.jpg?fit=800%2C578&ssl=1","width":800,"height":578},{"@type":"BreadcrumbList","@id":"https:\/\/empresasyeventos.com.uy\/index.php\/2025\/11\/13\/daniel-habif-llega-por-primera-vez-a-uruguay-con-su-ascender-world-tour-2025\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/empresasyeventos.com.uy\/"},{"@type":"ListItem","position":2,"name":"Daniel Habif llega por primera vez a Uruguay con su \u00abAscender World Tour 2025\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/empresasyeventos.com.uy\/#website","url":"https:\/\/empresasyeventos.com.uy\/","name":"Empresas &amp; Eventos","description":"Portal de noticias de Empresas y Eventos","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/empresasyeventos.com.uy\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/empresasyeventos.com.uy\/#\/schema\/person\/bad32f4c82dc0dcc552d9c237c4eabe2","name":"Alvaro","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/37aed957d094e6ff419d8d77fbf4778c8ca0066d25878f7d9ad4d0a724703223?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/37aed957d094e6ff419d8d77fbf4778c8ca0066d25878f7d9ad4d0a724703223?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/37aed957d094e6ff419d8d77fbf4778c8ca0066d25878f7d9ad4d0a724703223?s=96&d=mm&r=g","caption":"Alvaro"},"url":"https:\/\/empresasyeventos.com.uy\/index.php\/author\/alvaro\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/empresasyeventos.com.uy\/wp-content\/uploads\/2025\/11\/Daniel-Habif-e1763064209974.jpg?fit=800%2C578&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/empresasyeventos.com.uy\/index.php\/wp-json\/wp\/v2\/posts\/3640","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/empresasyeventos.com.uy\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/empresasyeventos.com.uy\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/empresasyeventos.com.uy\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/empresasyeventos.com.uy\/index.php\/wp-json\/wp\/v2\/comments?post=3640"}],"version-history":[{"count":1,"href":"https:\/\/empresasyeventos.com.uy\/index.php\/wp-json\/wp\/v2\/posts\/3640\/revisions"}],"predecessor-version":[{"id":3643,"href":"https:\/\/empresasyeventos.com.uy\/index.php\/wp-json\/wp\/v2\/posts\/3640\/revisions\/3643"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/empresasyeventos.com.uy\/index.php\/wp-json\/wp\/v2\/media\/3642"}],"wp:attachment":[{"href":"https:\/\/empresasyeventos.com.uy\/index.php\/wp-json\/wp\/v2\/media?parent=3640"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/empresasyeventos.com.uy\/index.php\/wp-json\/wp\/v2\/categories?post=3640"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/empresasyeventos.com.uy\/index.php\/wp-json\/wp\/v2\/tags?post=3640"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}